{"id":1980,"date":"2025-08-20T11:19:48","date_gmt":"2025-08-20T09:19:48","guid":{"rendered":"https:\/\/viventarealestate.es\/?post_type=vivienda&#038;p=1980"},"modified":"2026-01-12T19:26:26","modified_gmt":"2026-01-12T18:26:26","slug":"bello-horizonte-village","status":"publish","type":"vivienda","link":"https:\/\/viventarealestate.es\/nl\/viviendas\/bello-horizonte-village\/","title":{"rendered":"BELLO HORIZONTE VILLAGE 1e fase"},"content":{"rendered":"<p class=\"wp-block-paragraph\">5 Vrijstaande villa's in een unieke omgeving<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":0,"template":"","class_list":["post-1980","vivienda","type-vivienda","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuestra villa de lujo Bello Horizonte village - Viventa Real Estate<\/title>\n<meta name=\"description\" content=\"De las mejores Villas de lujo en toda la costa blanca, Bello Horizonte Village, es un lugar incre\u00edble para vivir y disfrutar del mediterr\u00e1neo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viventarealestate.es\/nl\/viviendas\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestra villa de lujo Bello Horizonte village - Viventa Real Estate\" \/>\n<meta property=\"og:description\" content=\"De las mejores Villas de lujo en toda la costa blanca, Bello Horizonte Village, es un lugar incre\u00edble para vivir y disfrutar del mediterr\u00e1neo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viventarealestate.es\/nl\/viviendas\/\" \/>\n<meta property=\"og:site_name\" content=\"Viventa Real Estate\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T18:26:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viventarealestate.es\/wp-content\/uploads\/2021\/12\/logo-Photoroom.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/viviendas\\\/bello-horizonte-village\\\/\",\"url\":\"https:\\\/\\\/viventarealestate.es\\\/viviendas\\\/\",\"name\":\"Nuestra villa de lujo Bello Horizonte village - Viventa Real Estate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/#website\"},\"datePublished\":\"2025-08-20T09:19:48+00:00\",\"dateModified\":\"2026-01-12T18:26:26+00:00\",\"description\":\"De las mejores Villas de lujo en toda la costa blanca, Bello Horizonte Village, es un lugar incre\u00edble para vivir y disfrutar del mediterr\u00e1neo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/viviendas\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/viventarealestate.es\\\/viviendas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/viviendas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/viventarealestate.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viviendas\",\"item\":\"https:\\\/\\\/viventarealestate.es\\\/en\\\/viviendas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inicio > Viviendas disponibles en la Costa Blanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/\",\"name\":\"Viventa Real Estate\",\"description\":\"Empresa inmobiliaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/#organization\"},\"alternateName\":\"Viviendas de lujo en la Costa Blanca y Villas exclusivas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/#organization\",\"name\":\"Viventa Real Estate\",\"alternateName\":\"Viventa Real Estate S.L\",\"url\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/viventarealestate.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo-Photoroom.png\",\"contentUrl\":\"https:\\\/\\\/viventarealestate.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo-Photoroom.png\",\"width\":1280,\"height\":444,\"caption\":\"Viventa Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/viventarealestate.es\\\/zh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestra villa de lujo Bello Horizonte village - Viventa Real Estate","description":"De las mejores Villas de lujo en toda la costa blanca, Bello Horizonte Village, es un lugar incre\u00edble para vivir y disfrutar del mediterr\u00e1neo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viventarealestate.es\/nl\/viviendas\/","og_locale":"nl_NL","og_type":"article","og_title":"Nuestra villa de lujo Bello Horizonte village - Viventa Real Estate","og_description":"De las mejores Villas de lujo en toda la costa blanca, Bello Horizonte Village, es un lugar incre\u00edble para vivir y disfrutar del mediterr\u00e1neo","og_url":"https:\/\/viventarealestate.es\/nl\/viviendas\/","og_site_name":"Viventa Real Estate","article_modified_time":"2026-01-12T18:26:26+00:00","og_image":[{"width":1280,"height":444,"url":"https:\/\/viventarealestate.es\/wp-content\/uploads\/2021\/12\/logo-Photoroom.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/viventarealestate.es\/viviendas\/bello-horizonte-village\/","url":"https:\/\/viventarealestate.es\/viviendas\/","name":"Nuestra villa de lujo Bello Horizonte village - Viventa Real Estate","isPartOf":{"@id":"https:\/\/viventarealestate.es\/zh\/#website"},"datePublished":"2025-08-20T09:19:48+00:00","dateModified":"2026-01-12T18:26:26+00:00","description":"De las mejores Villas de lujo en toda la costa blanca, Bello Horizonte Village, es un lugar incre\u00edble para vivir y disfrutar del mediterr\u00e1neo","breadcrumb":{"@id":"https:\/\/viventarealestate.es\/viviendas\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viventarealestate.es\/viviendas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/viventarealestate.es\/viviendas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/viventarealestate.es\/"},{"@type":"ListItem","position":2,"name":"Viviendas","item":"https:\/\/viventarealestate.es\/en\/viviendas\/"},{"@type":"ListItem","position":3,"name":"Inicio > Viviendas disponibles en la Costa Blanca"}]},{"@type":"WebSite","@id":"https:\/\/viventarealestate.es\/zh\/#website","url":"https:\/\/viventarealestate.es\/zh\/","name":"Viventa Real Estate","description":"Empresa inmobiliaria","publisher":{"@id":"https:\/\/viventarealestate.es\/zh\/#organization"},"alternateName":"Viviendas de lujo en la Costa Blanca y Villas exclusivas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viventarealestate.es\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/viventarealestate.es\/zh\/#organization","name":"Viventa Real Estate","alternateName":"Viventa Real Estate S.L","url":"https:\/\/viventarealestate.es\/zh\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/viventarealestate.es\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/viventarealestate.es\/wp-content\/uploads\/2021\/12\/logo-Photoroom.png","contentUrl":"https:\/\/viventarealestate.es\/wp-content\/uploads\/2021\/12\/logo-Photoroom.png","width":1280,"height":444,"caption":"Viventa Real Estate"},"image":{"@id":"https:\/\/viventarealestate.es\/zh\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/viventarealestate.es\/nl\/wp-json\/wp\/v2\/vivienda\/1980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viventarealestate.es\/nl\/wp-json\/wp\/v2\/vivienda"}],"about":[{"href":"https:\/\/viventarealestate.es\/nl\/wp-json\/wp\/v2\/types\/vivienda"}],"version-history":[{"count":5,"href":"https:\/\/viventarealestate.es\/nl\/wp-json\/wp\/v2\/vivienda\/1980\/revisions"}],"predecessor-version":[{"id":2074,"href":"https:\/\/viventarealestate.es\/nl\/wp-json\/wp\/v2\/vivienda\/1980\/revisions\/2074"}],"wp:attachment":[{"href":"https:\/\/viventarealestate.es\/nl\/wp-json\/wp\/v2\/media?parent=1980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}